{"id":43232,"date":"2023-11-08T11:38:26","date_gmt":"2023-11-08T03:38:26","guid":{"rendered":"https:\/\/beyondactiv.com\/events\/?post_type=all_speakers&#038;p=43232"},"modified":"2024-01-05T00:27:41","modified_gmt":"2024-01-04T16:27:41","slug":"al-noshirvani","status":"publish","type":"all_speakers","link":"https:\/\/beyondactiv.com\/events\/th\/speakers\/al-noshirvani\/","title":{"rendered":"\u0e2d\u0e31\u0e25 \u0e42\u0e19\u0e0a\u0e34\u0e23\u0e4c\u0e27\u0e32\u0e19\u0e35"},"content":{"rendered":"<h3 class=\"wp-block-heading\">\u0e2d\u0e31\u0e25 \u0e42\u0e19\u0e0a\u0e34\u0e23\u0e4c\u0e27\u0e32\u0e19\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48 <a href=\"https:\/\/getalta.com\/\" data-type=\"link\" data-id=\"https:\/\/getalta.com\/\" target=\"_blank\" rel=\"noopener\">\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 ALTA<\/a>, \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 HALO (\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e, \u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07). <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27 ALTA \u0e04\u0e38\u0e13 Al \u0e40\u0e04\u0e22\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 Motionsoft Inc. \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e02\u0e32\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e19\u0e1b\u0e35 2010 \u0e04\u0e38\u0e13 Al \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e0a\u0e37\u0e48\u0e2d\u0e08\u0e32\u0e01 Washington Business Journal \u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19 40 Under 40 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e22\u0e01\u0e22\u0e48\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 Greater Washington \u0e42\u0e14\u0e22\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e41\u0e2a\u0e14\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19 \u0e43\u0e19\u0e1b\u0e35 2014 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 Al \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 Motionsoft \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19 IHRSA Associate Member of the Year \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e04\u0e38\u0e13 Al \u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07 Fitness Technology Summit \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e34\u0e0d\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e08\u0e30\u0e21\u0e32\u0e23\u0e27\u0e21\u0e15\u0e31\u0e27\u0e01\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32 3 \u0e27\u0e31\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e40\u0e0b\u0e2a\u0e0a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e20\u0e34\u0e1b\u0e23\u0e32\u0e22\u0e40\u0e0a\u0e34\u0e07\u0e25\u0e36\u0e01 \u0e40\u0e02\u0e32\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 Entrepreneur in Residence \u0e01\u0e31\u0e1a Integrity Square \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e32\u0e13\u0e34\u0e0a\u0e18\u0e19\u0e01\u0e34\u0e08\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e42\u0e14\u0e22\u0e40\u0e02\u0e32\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19 Fitech \u0e41\u0e25\u0e30 SaaS applications \u0e04\u0e38\u0e13 Al \u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a\u0e04\u0e25\u0e31\u0e1a\u0e43\u0e19\u0e40\u0e02\u0e15\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 Greater Washington DC \u0e0a\u0e37\u0e48\u0e2d Method Gyms.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e14\u0e34\u0e21\u0e17\u0e35 \u0e40\u0e2d\u0e25\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e23\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1d\u0e48\u0e32\u0e22\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e02\u0e32\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e01\u0e44\u0e1b \u0e40\u0e02\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e42\u0e17\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e40\u0e02\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e40\u0e17\u0e19\u0e19\u0e34\u0e2a\u0e17\u0e35\u0e48\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e41\u0e21\u0e23\u0e34\u0e41\u0e25\u0e19\u0e14\u0e4c.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2d\u0e31\u0e25 \u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1e\u0e39\u0e14\u0e17\u0e35\u0e48 <a href=\"https:\/\/beyondactiv.com\/events\/th\/americas\/\">Beyond Activ AMERICAS<\/a> \u0e43\u0e19\u0e19\u0e34\u0e27\u0e22\u0e2d\u0e23\u0e4c\u0e01 \u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u0e1c\u0e39\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23<\/p>\n<h5>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 ALTA<\/h5>","protected":false},"featured_media":43233,"template":"","speakers-type":[59],"class_list":["post-43232","all_speakers","type-all_speakers","status-publish","has-post-thumbnail","hentry","speakers-type-2024-americas-speakers-confirmed"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"_links":{"self":[{"href":"https:\/\/beyondactiv.com\/events\/th\/wp-json\/wp\/v2\/all_speakers\/43232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beyondactiv.com\/events\/th\/wp-json\/wp\/v2\/all_speakers"}],"about":[{"href":"https:\/\/beyondactiv.com\/events\/th\/wp-json\/wp\/v2\/types\/all_speakers"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beyondactiv.com\/events\/th\/wp-json\/wp\/v2\/media\/43233"}],"wp:attachment":[{"href":"https:\/\/beyondactiv.com\/events\/th\/wp-json\/wp\/v2\/media?parent=43232"}],"wp:term":[{"taxonomy":"speakers-type","embeddable":true,"href":"https:\/\/beyondactiv.com\/events\/th\/wp-json\/wp\/v2\/speakers-type?post=43232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}